{"id":884,"count":0,"description":"","link":"https:\/\/www.clubempleos.com\/chile\/trabajo-categoria\/agente-de-seguros\/","name":"Agente de seguros","slug":"agente-de-seguros","taxonomy":"job_listing_category","parent":881,"meta":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.3 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Trabajos de Agente de seguros - Empleos - Vacantes | ClubEmpleos Chile<\/title>\n<meta name=\"description\" content=\"Trabajos de Agente de seguros, encuentre empleos en nuestra bolsa de trabajo. Vacantes diariamente en las empresas.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.clubempleos.com\/chile\/trabajo-categoria\/agente-de-seguros\/\" \/>\n<meta property=\"og:locale\" content=\"es_MX\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Trabajos de Agente de seguros - Empleos - Vacantes | ClubEmpleos Chile\" \/>\n<meta property=\"og:description\" content=\"Trabajos de Agente de seguros, encuentre empleos en nuestra bolsa de trabajo. Vacantes diariamente en las empresas.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.clubempleos.com\/chile\/trabajo-categoria\/agente-de-seguros\/\" \/>\n<meta property=\"og:site_name\" content=\"ClubEmpleos Chile\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.clubempleos.com\/chile\/wp-content\/uploads\/sites\/8\/2025\/09\/default-featured-image-clubempleos-chile.png\" \/>\n\t<meta property=\"og:image:width\" content=\"1920\" \/>\n\t<meta property=\"og:image:height\" content=\"1080\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/png\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:site\" content=\"@clubempleos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"CollectionPage\",\"@id\":\"https:\\\/\\\/www.clubempleos.com\\\/chile\\\/trabajo-categoria\\\/agente-de-seguros\\\/\",\"url\":\"https:\\\/\\\/www.clubempleos.com\\\/chile\\\/trabajo-categoria\\\/agente-de-seguros\\\/\",\"name\":\"Trabajos de Agente de seguros - Empleos - Vacantes | ClubEmpleos Chile\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.clubempleos.com\\\/chile\\\/#website\"},\"description\":\"Trabajos de Agente de seguros, encuentre empleos en nuestra bolsa de trabajo. Vacantes diariamente en las empresas.\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.clubempleos.com\\\/chile\\\/trabajo-categoria\\\/agente-de-seguros\\\/#breadcrumb\"},\"inLanguage\":\"es-MX\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.clubempleos.com\\\/chile\\\/trabajo-categoria\\\/agente-de-seguros\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Inicio\",\"item\":\"https:\\\/\\\/www.clubempleos.com\\\/chile\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Empleos\",\"item\":\"https:\\\/\\\/www.clubempleos.com\\\/chile\\\/trabajos\\\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"Seguros y reaseguros\",\"item\":\"https:\\\/\\\/www.clubempleos.com\\\/chile\\\/trabajo-categoria\\\/seguros-y-reaseguros\\\/\"},{\"@type\":\"ListItem\",\"position\":4,\"name\":\"Agente de seguros\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.clubempleos.com\\\/chile\\\/#website\",\"url\":\"https:\\\/\\\/www.clubempleos.com\\\/chile\\\/\",\"name\":\"ClubEmpleos Chile\",\"description\":\"Bolsa nacional de empleo y trabajo | ClubEmpleos Chile\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.clubempleos.com\\\/chile\\\/#organization\"},\"alternateName\":\"Club Empleos Chile\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.clubempleos.com\\\/chile\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es-MX\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/www.clubempleos.com\\\/chile\\\/#organization\",\"name\":\"ClubEmpleos Chile\",\"alternateName\":\"Club Empleos Chile\",\"url\":\"https:\\\/\\\/www.clubempleos.com\\\/chile\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es-MX\",\"@id\":\"https:\\\/\\\/www.clubempleos.com\\\/chile\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/www.clubempleos.com\\\/chile\\\/wp-content\\\/uploads\\\/sites\\\/8\\\/2024\\\/08\\\/logo-de-la-organizacion.jpg\",\"contentUrl\":\"https:\\\/\\\/www.clubempleos.com\\\/chile\\\/wp-content\\\/uploads\\\/sites\\\/8\\\/2024\\\/08\\\/logo-de-la-organizacion.jpg\",\"width\":696,\"height\":696,\"caption\":\"ClubEmpleos Chile\"},\"image\":{\"@id\":\"https:\\\/\\\/www.clubempleos.com\\\/chile\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/clubempleos.chile\\\/\",\"https:\\\/\\\/x.com\\\/clubempleos\"]}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Trabajos de Agente de seguros - Empleos - Vacantes | ClubEmpleos Chile","description":"Trabajos de Agente de seguros, encuentre empleos en nuestra bolsa de trabajo. Vacantes diariamente en las empresas.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.clubempleos.com\/chile\/trabajo-categoria\/agente-de-seguros\/","og_locale":"es_MX","og_type":"article","og_title":"Trabajos de Agente de seguros - Empleos - Vacantes | ClubEmpleos Chile","og_description":"Trabajos de Agente de seguros, encuentre empleos en nuestra bolsa de trabajo. Vacantes diariamente en las empresas.","og_url":"https:\/\/www.clubempleos.com\/chile\/trabajo-categoria\/agente-de-seguros\/","og_site_name":"ClubEmpleos Chile","og_image":[{"width":1920,"height":1080,"url":"https:\/\/www.clubempleos.com\/chile\/wp-content\/uploads\/sites\/8\/2025\/09\/default-featured-image-clubempleos-chile.png","type":"image\/png"}],"twitter_card":"summary_large_image","twitter_site":"@clubempleos","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"CollectionPage","@id":"https:\/\/www.clubempleos.com\/chile\/trabajo-categoria\/agente-de-seguros\/","url":"https:\/\/www.clubempleos.com\/chile\/trabajo-categoria\/agente-de-seguros\/","name":"Trabajos de Agente de seguros - Empleos - Vacantes | ClubEmpleos Chile","isPartOf":{"@id":"https:\/\/www.clubempleos.com\/chile\/#website"},"description":"Trabajos de Agente de seguros, encuentre empleos en nuestra bolsa de trabajo. Vacantes diariamente en las empresas.","breadcrumb":{"@id":"https:\/\/www.clubempleos.com\/chile\/trabajo-categoria\/agente-de-seguros\/#breadcrumb"},"inLanguage":"es-MX"},{"@type":"BreadcrumbList","@id":"https:\/\/www.clubempleos.com\/chile\/trabajo-categoria\/agente-de-seguros\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Inicio","item":"https:\/\/www.clubempleos.com\/chile\/"},{"@type":"ListItem","position":2,"name":"Empleos","item":"https:\/\/www.clubempleos.com\/chile\/trabajos\/"},{"@type":"ListItem","position":3,"name":"Seguros y reaseguros","item":"https:\/\/www.clubempleos.com\/chile\/trabajo-categoria\/seguros-y-reaseguros\/"},{"@type":"ListItem","position":4,"name":"Agente de seguros"}]},{"@type":"WebSite","@id":"https:\/\/www.clubempleos.com\/chile\/#website","url":"https:\/\/www.clubempleos.com\/chile\/","name":"ClubEmpleos Chile","description":"Bolsa nacional de empleo y trabajo | ClubEmpleos Chile","publisher":{"@id":"https:\/\/www.clubempleos.com\/chile\/#organization"},"alternateName":"Club Empleos Chile","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.clubempleos.com\/chile\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es-MX"},{"@type":"Organization","@id":"https:\/\/www.clubempleos.com\/chile\/#organization","name":"ClubEmpleos Chile","alternateName":"Club Empleos Chile","url":"https:\/\/www.clubempleos.com\/chile\/","logo":{"@type":"ImageObject","inLanguage":"es-MX","@id":"https:\/\/www.clubempleos.com\/chile\/#\/schema\/logo\/image\/","url":"https:\/\/www.clubempleos.com\/chile\/wp-content\/uploads\/sites\/8\/2024\/08\/logo-de-la-organizacion.jpg","contentUrl":"https:\/\/www.clubempleos.com\/chile\/wp-content\/uploads\/sites\/8\/2024\/08\/logo-de-la-organizacion.jpg","width":696,"height":696,"caption":"ClubEmpleos Chile"},"image":{"@id":"https:\/\/www.clubempleos.com\/chile\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/clubempleos.chile\/","https:\/\/x.com\/clubempleos"]}]}},"_links":{"self":[{"href":"https:\/\/www.clubempleos.com\/chile\/wp-json\/wp\/v2\/job-categories\/884","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.clubempleos.com\/chile\/wp-json\/wp\/v2\/job-categories"}],"about":[{"href":"https:\/\/www.clubempleos.com\/chile\/wp-json\/wp\/v2\/taxonomies\/job_listing_category"}],"up":[{"embeddable":true,"href":"https:\/\/www.clubempleos.com\/chile\/wp-json\/wp\/v2\/job-categories\/881"}],"wp:post_type":[{"href":"https:\/\/www.clubempleos.com\/chile\/wp-json\/wp\/v2\/job-listings?job-categories=884"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}