{"id":1157,"date":"2026-08-14T20:00:00","date_gmt":"2026-08-14T20:00:00","guid":{"rendered":"https:\/\/www.clubempleos.com\/chile\/?post_type=job_listing&#038;p=1157"},"modified":"2026-07-29T11:02:08","modified_gmt":"2026-07-29T15:02:08","slug":"boca-spa-la-serena-209-maestra-o-maestro-de-cocina","status":"publish","type":"job_listing","link":"https:\/\/www.clubempleos.com\/chile\/trabajo\/boca-spa-la-serena-209-maestra-o-maestro-de-cocina\/","title":{"rendered":"Maestra o maestro de cocina"},"content":{"rendered":"<p>Se busca maestra o maestro de cocina con experiencia en el cargo m\u00ednimo 1 a\u00f1o para restaurante en avda Aguirre 096 La Serena. Trabajo estable, sueldo de mercado m\u00e1s propinas, horario de martes a domingo. Interesados enviar cv al mail o ws 951256990<\/p>\n","protected":false},"author":4614,"featured_media":0,"template":"","meta":{"_promoted":"","_job_location":"La Serena","_application":"rebolledodinamarca@gmail.com","_company_name":"Boca spa","_company_website":"","_company_tagline":"Pyme con promedio de 5 personas en total, restaurante familiar con trayectoria","_company_twitter":"","_company_video":"","_filled":0,"_featured":0,"_remote_position":0,"_job_salary":"","_job_salary_currency":"","_job_salary_unit":"MONTH"},"job-categories":[937],"job-types":[209],"job_listing_tag":[1365,1368],"class_list":["post-1157","job_listing","type-job_listing","status-publish","hentry","job_listing_category-cocina","job_listing_type-tiempo-completo","job_listing_tag-responsabilidad","job_listing_tag-trabajo-en-equipo","job-type-tiempo-completo"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.3 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Trabajo de Maestra o maestro de cocina | ClubEmpleos Chile<\/title>\n<meta name=\"description\" content=\"Trabajo de Maestra o maestro de cocina, encuentre empleo en nuestra bolsa de trabajo. \u00a1Suba su curriculum vitae hoy y post\u00falese a la vacante!\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.clubempleos.com\/chile\/trabajo\/boca-spa-la-serena-209-maestra-o-maestro-de-cocina\/\" \/>\n<meta property=\"og:locale\" content=\"es_MX\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Trabajo de Maestra o maestro de cocina | ClubEmpleos Chile\" \/>\n<meta property=\"og:description\" content=\"Trabajo de Maestra o maestro de cocina, encuentre empleo en nuestra bolsa de trabajo. \u00a1Suba su curriculum vitae hoy y post\u00falese a la vacante!\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.clubempleos.com\/chile\/trabajo\/boca-spa-la-serena-209-maestra-o-maestro-de-cocina\/\" \/>\n<meta property=\"og:site_name\" content=\"ClubEmpleos Chile\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/clubempleos.chile\/\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.clubempleos.com\/chile\/wp-content\/uploads\/sites\/8\/2025\/09\/default-featured-image-clubempleos-chile.png\" \/>\n\t<meta property=\"og:image:width\" content=\"1920\" \/>\n\t<meta property=\"og:image:height\" content=\"1080\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/png\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:site\" content=\"@clubempleos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.clubempleos.com\\\/chile\\\/trabajo\\\/boca-spa-la-serena-209-maestra-o-maestro-de-cocina\\\/\",\"url\":\"https:\\\/\\\/www.clubempleos.com\\\/chile\\\/trabajo\\\/boca-spa-la-serena-209-maestra-o-maestro-de-cocina\\\/\",\"name\":\"Trabajo de Maestra o maestro de cocina | ClubEmpleos Chile\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.clubempleos.com\\\/chile\\\/#website\"},\"datePublished\":\"2026-08-14T20:00:00+00:00\",\"description\":\"Trabajo de Maestra o maestro de cocina, encuentre empleo en nuestra bolsa de trabajo. \u00a1Suba su curriculum vitae hoy y post\u00falese a la vacante!\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.clubempleos.com\\\/chile\\\/trabajo\\\/boca-spa-la-serena-209-maestra-o-maestro-de-cocina\\\/#breadcrumb\"},\"inLanguage\":\"es-MX\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.clubempleos.com\\\/chile\\\/trabajo\\\/boca-spa-la-serena-209-maestra-o-maestro-de-cocina\\\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.clubempleos.com\\\/chile\\\/trabajo\\\/boca-spa-la-serena-209-maestra-o-maestro-de-cocina\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Inicio\",\"item\":\"https:\\\/\\\/www.clubempleos.com\\\/chile\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Empleos\",\"item\":\"https:\\\/\\\/www.clubempleos.com\\\/chile\\\/trabajos\\\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"Maestra o maestro de cocina\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.clubempleos.com\\\/chile\\\/#website\",\"url\":\"https:\\\/\\\/www.clubempleos.com\\\/chile\\\/\",\"name\":\"ClubEmpleos Chile\",\"description\":\"Bolsa nacional de empleo y trabajo | ClubEmpleos Chile\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.clubempleos.com\\\/chile\\\/#organization\"},\"alternateName\":\"Club Empleos Chile\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.clubempleos.com\\\/chile\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es-MX\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/www.clubempleos.com\\\/chile\\\/#organization\",\"name\":\"ClubEmpleos Chile\",\"alternateName\":\"Club Empleos Chile\",\"url\":\"https:\\\/\\\/www.clubempleos.com\\\/chile\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es-MX\",\"@id\":\"https:\\\/\\\/www.clubempleos.com\\\/chile\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/www.clubempleos.com\\\/chile\\\/wp-content\\\/uploads\\\/sites\\\/8\\\/2024\\\/08\\\/logo-de-la-organizacion.jpg\",\"contentUrl\":\"https:\\\/\\\/www.clubempleos.com\\\/chile\\\/wp-content\\\/uploads\\\/sites\\\/8\\\/2024\\\/08\\\/logo-de-la-organizacion.jpg\",\"width\":696,\"height\":696,\"caption\":\"ClubEmpleos Chile\"},\"image\":{\"@id\":\"https:\\\/\\\/www.clubempleos.com\\\/chile\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/clubempleos.chile\\\/\",\"https:\\\/\\\/x.com\\\/clubempleos\"]}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Trabajo de Maestra o maestro de cocina | ClubEmpleos Chile","description":"Trabajo de Maestra o maestro de cocina, encuentre empleo en nuestra bolsa de trabajo. \u00a1Suba su curriculum vitae hoy y post\u00falese a la vacante!","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.clubempleos.com\/chile\/trabajo\/boca-spa-la-serena-209-maestra-o-maestro-de-cocina\/","og_locale":"es_MX","og_type":"article","og_title":"Trabajo de Maestra o maestro de cocina | ClubEmpleos Chile","og_description":"Trabajo de Maestra o maestro de cocina, encuentre empleo en nuestra bolsa de trabajo. \u00a1Suba su curriculum vitae hoy y post\u00falese a la vacante!","og_url":"https:\/\/www.clubempleos.com\/chile\/trabajo\/boca-spa-la-serena-209-maestra-o-maestro-de-cocina\/","og_site_name":"ClubEmpleos Chile","article_publisher":"https:\/\/www.facebook.com\/clubempleos.chile\/","og_image":[{"width":1920,"height":1080,"url":"https:\/\/www.clubempleos.com\/chile\/wp-content\/uploads\/sites\/8\/2025\/09\/default-featured-image-clubempleos-chile.png","type":"image\/png"}],"twitter_card":"summary_large_image","twitter_site":"@clubempleos","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/www.clubempleos.com\/chile\/trabajo\/boca-spa-la-serena-209-maestra-o-maestro-de-cocina\/","url":"https:\/\/www.clubempleos.com\/chile\/trabajo\/boca-spa-la-serena-209-maestra-o-maestro-de-cocina\/","name":"Trabajo de Maestra o maestro de cocina | ClubEmpleos Chile","isPartOf":{"@id":"https:\/\/www.clubempleos.com\/chile\/#website"},"datePublished":"2026-08-14T20:00:00+00:00","description":"Trabajo de Maestra o maestro de cocina, encuentre empleo en nuestra bolsa de trabajo. \u00a1Suba su curriculum vitae hoy y post\u00falese a la vacante!","breadcrumb":{"@id":"https:\/\/www.clubempleos.com\/chile\/trabajo\/boca-spa-la-serena-209-maestra-o-maestro-de-cocina\/#breadcrumb"},"inLanguage":"es-MX","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.clubempleos.com\/chile\/trabajo\/boca-spa-la-serena-209-maestra-o-maestro-de-cocina\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/www.clubempleos.com\/chile\/trabajo\/boca-spa-la-serena-209-maestra-o-maestro-de-cocina\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Inicio","item":"https:\/\/www.clubempleos.com\/chile\/"},{"@type":"ListItem","position":2,"name":"Empleos","item":"https:\/\/www.clubempleos.com\/chile\/trabajos\/"},{"@type":"ListItem","position":3,"name":"Maestra o maestro de cocina"}]},{"@type":"WebSite","@id":"https:\/\/www.clubempleos.com\/chile\/#website","url":"https:\/\/www.clubempleos.com\/chile\/","name":"ClubEmpleos Chile","description":"Bolsa nacional de empleo y trabajo | ClubEmpleos Chile","publisher":{"@id":"https:\/\/www.clubempleos.com\/chile\/#organization"},"alternateName":"Club Empleos Chile","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.clubempleos.com\/chile\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es-MX"},{"@type":"Organization","@id":"https:\/\/www.clubempleos.com\/chile\/#organization","name":"ClubEmpleos Chile","alternateName":"Club Empleos Chile","url":"https:\/\/www.clubempleos.com\/chile\/","logo":{"@type":"ImageObject","inLanguage":"es-MX","@id":"https:\/\/www.clubempleos.com\/chile\/#\/schema\/logo\/image\/","url":"https:\/\/www.clubempleos.com\/chile\/wp-content\/uploads\/sites\/8\/2024\/08\/logo-de-la-organizacion.jpg","contentUrl":"https:\/\/www.clubempleos.com\/chile\/wp-content\/uploads\/sites\/8\/2024\/08\/logo-de-la-organizacion.jpg","width":696,"height":696,"caption":"ClubEmpleos Chile"},"image":{"@id":"https:\/\/www.clubempleos.com\/chile\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/clubempleos.chile\/","https:\/\/x.com\/clubempleos"]}]}},"_links":{"self":[{"href":"https:\/\/www.clubempleos.com\/chile\/wp-json\/wp\/v2\/job-listings\/1157","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.clubempleos.com\/chile\/wp-json\/wp\/v2\/job-listings"}],"about":[{"href":"https:\/\/www.clubempleos.com\/chile\/wp-json\/wp\/v2\/types\/job_listing"}],"author":[{"embeddable":true,"href":"https:\/\/www.clubempleos.com\/chile\/wp-json\/wp\/v2\/users\/4614"}],"wp:attachment":[{"href":"https:\/\/www.clubempleos.com\/chile\/wp-json\/wp\/v2\/media?parent=1157"}],"wp:term":[{"taxonomy":"job_listing_category","embeddable":true,"href":"https:\/\/www.clubempleos.com\/chile\/wp-json\/wp\/v2\/job-categories?post=1157"},{"taxonomy":"job_listing_type","embeddable":true,"href":"https:\/\/www.clubempleos.com\/chile\/wp-json\/wp\/v2\/job-types?post=1157"},{"taxonomy":"job_listing_tag","embeddable":true,"href":"https:\/\/www.clubempleos.com\/chile\/wp-json\/wp\/v2\/job_listing_tag?post=1157"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}