{"id":626,"count":0,"description":"","link":"https:\/\/www.clubempleos.com\/colombia\/trabajo-categoria\/recepcion-y-operacion\/","name":"Recepci\u00f3n y operaci\u00f3n","slug":"recepcion-y-operacion","taxonomy":"job_listing_category","parent":613,"meta":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.3 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Trabajos de Recepci\u00f3n y operaci\u00f3n - Empleos - Vacantes | ClubEmpleos Colombia<\/title>\n<meta name=\"description\" content=\"Trabajos de Recepci\u00f3n y operaci\u00f3n, encuentre empleos en nuestra bolsa de trabajo. Vacantes diariamente en las empresas.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.clubempleos.com\/colombia\/trabajo-categoria\/recepcion-y-operacion\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Trabajos de Recepci\u00f3n y operaci\u00f3n - Empleos - Vacantes | ClubEmpleos Colombia\" \/>\n<meta property=\"og:description\" content=\"Trabajos de Recepci\u00f3n y operaci\u00f3n, encuentre empleos en nuestra bolsa de trabajo. Vacantes diariamente en las empresas.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.clubempleos.com\/colombia\/trabajo-categoria\/recepcion-y-operacion\/\" \/>\n<meta property=\"og:site_name\" content=\"ClubEmpleos Colombia\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.clubempleos.com\/colombia\/wp-content\/uploads\/sites\/9\/2025\/09\/default-featured-image-clubempleos-colombia.png\" \/>\n\t<meta property=\"og:image:width\" content=\"1920\" \/>\n\t<meta property=\"og:image:height\" content=\"1080\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/png\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:site\" content=\"@clubempleos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"CollectionPage\",\"@id\":\"https:\\\/\\\/www.clubempleos.com\\\/colombia\\\/trabajo-categoria\\\/recepcion-y-operacion\\\/\",\"url\":\"https:\\\/\\\/www.clubempleos.com\\\/colombia\\\/trabajo-categoria\\\/recepcion-y-operacion\\\/\",\"name\":\"Trabajos de Recepci\u00f3n y operaci\u00f3n - Empleos - Vacantes | ClubEmpleos Colombia\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.clubempleos.com\\\/colombia\\\/#website\"},\"description\":\"Trabajos de Recepci\u00f3n y operaci\u00f3n, encuentre empleos en nuestra bolsa de trabajo. Vacantes diariamente en las empresas.\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.clubempleos.com\\\/colombia\\\/trabajo-categoria\\\/recepcion-y-operacion\\\/#breadcrumb\"},\"inLanguage\":\"es-CO\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.clubempleos.com\\\/colombia\\\/trabajo-categoria\\\/recepcion-y-operacion\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Inicio\",\"item\":\"https:\\\/\\\/www.clubempleos.com\\\/colombia\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Empleos\",\"item\":\"https:\\\/\\\/www.clubempleos.com\\\/colombia\\\/trabajos\\\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"Administrativo\",\"item\":\"https:\\\/\\\/www.clubempleos.com\\\/colombia\\\/trabajo-categoria\\\/administrativo\\\/\"},{\"@type\":\"ListItem\",\"position\":4,\"name\":\"Recepci\u00f3n y operaci\u00f3n\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.clubempleos.com\\\/colombia\\\/#website\",\"url\":\"https:\\\/\\\/www.clubempleos.com\\\/colombia\\\/\",\"name\":\"ClubEmpleos Colombia\",\"description\":\"Bolsa del Empleo y Portal del Empleo en Colombia. Avisos clasificados de empleos y anuncios de trabajo gratis. Encuentra ofertas de empleo.\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.clubempleos.com\\\/colombia\\\/#organization\"},\"alternateName\":\"Club Empleos Colombia\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.clubempleos.com\\\/colombia\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es-CO\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/www.clubempleos.com\\\/colombia\\\/#organization\",\"name\":\"ClubEmpleos\",\"alternateName\":\"Club Empleos\",\"url\":\"https:\\\/\\\/www.clubempleos.com\\\/colombia\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es-CO\",\"@id\":\"https:\\\/\\\/www.clubempleos.com\\\/colombia\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/www.clubempleos.com\\\/colombia\\\/wp-content\\\/uploads\\\/sites\\\/9\\\/2024\\\/08\\\/logo-de-la-organizacion.jpg\",\"contentUrl\":\"https:\\\/\\\/www.clubempleos.com\\\/colombia\\\/wp-content\\\/uploads\\\/sites\\\/9\\\/2024\\\/08\\\/logo-de-la-organizacion.jpg\",\"width\":696,\"height\":696,\"caption\":\"ClubEmpleos\"},\"image\":{\"@id\":\"https:\\\/\\\/www.clubempleos.com\\\/colombia\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/clubempleos.colombia\\\/\",\"https:\\\/\\\/x.com\\\/clubempleos\"]}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Trabajos de Recepci\u00f3n y operaci\u00f3n - Empleos - Vacantes | ClubEmpleos Colombia","description":"Trabajos de Recepci\u00f3n y operaci\u00f3n, encuentre empleos en nuestra bolsa de trabajo. Vacantes diariamente en las empresas.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.clubempleos.com\/colombia\/trabajo-categoria\/recepcion-y-operacion\/","og_locale":"es_ES","og_type":"article","og_title":"Trabajos de Recepci\u00f3n y operaci\u00f3n - Empleos - Vacantes | ClubEmpleos Colombia","og_description":"Trabajos de Recepci\u00f3n y operaci\u00f3n, encuentre empleos en nuestra bolsa de trabajo. Vacantes diariamente en las empresas.","og_url":"https:\/\/www.clubempleos.com\/colombia\/trabajo-categoria\/recepcion-y-operacion\/","og_site_name":"ClubEmpleos Colombia","og_image":[{"width":1920,"height":1080,"url":"https:\/\/www.clubempleos.com\/colombia\/wp-content\/uploads\/sites\/9\/2025\/09\/default-featured-image-clubempleos-colombia.png","type":"image\/png"}],"twitter_card":"summary_large_image","twitter_site":"@clubempleos","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"CollectionPage","@id":"https:\/\/www.clubempleos.com\/colombia\/trabajo-categoria\/recepcion-y-operacion\/","url":"https:\/\/www.clubempleos.com\/colombia\/trabajo-categoria\/recepcion-y-operacion\/","name":"Trabajos de Recepci\u00f3n y operaci\u00f3n - Empleos - Vacantes | ClubEmpleos Colombia","isPartOf":{"@id":"https:\/\/www.clubempleos.com\/colombia\/#website"},"description":"Trabajos de Recepci\u00f3n y operaci\u00f3n, encuentre empleos en nuestra bolsa de trabajo. Vacantes diariamente en las empresas.","breadcrumb":{"@id":"https:\/\/www.clubempleos.com\/colombia\/trabajo-categoria\/recepcion-y-operacion\/#breadcrumb"},"inLanguage":"es-CO"},{"@type":"BreadcrumbList","@id":"https:\/\/www.clubempleos.com\/colombia\/trabajo-categoria\/recepcion-y-operacion\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Inicio","item":"https:\/\/www.clubempleos.com\/colombia\/"},{"@type":"ListItem","position":2,"name":"Empleos","item":"https:\/\/www.clubempleos.com\/colombia\/trabajos\/"},{"@type":"ListItem","position":3,"name":"Administrativo","item":"https:\/\/www.clubempleos.com\/colombia\/trabajo-categoria\/administrativo\/"},{"@type":"ListItem","position":4,"name":"Recepci\u00f3n y operaci\u00f3n"}]},{"@type":"WebSite","@id":"https:\/\/www.clubempleos.com\/colombia\/#website","url":"https:\/\/www.clubempleos.com\/colombia\/","name":"ClubEmpleos Colombia","description":"Bolsa del Empleo y Portal del Empleo en Colombia. Avisos clasificados de empleos y anuncios de trabajo gratis. Encuentra ofertas de empleo.","publisher":{"@id":"https:\/\/www.clubempleos.com\/colombia\/#organization"},"alternateName":"Club Empleos Colombia","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.clubempleos.com\/colombia\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es-CO"},{"@type":"Organization","@id":"https:\/\/www.clubempleos.com\/colombia\/#organization","name":"ClubEmpleos","alternateName":"Club Empleos","url":"https:\/\/www.clubempleos.com\/colombia\/","logo":{"@type":"ImageObject","inLanguage":"es-CO","@id":"https:\/\/www.clubempleos.com\/colombia\/#\/schema\/logo\/image\/","url":"https:\/\/www.clubempleos.com\/colombia\/wp-content\/uploads\/sites\/9\/2024\/08\/logo-de-la-organizacion.jpg","contentUrl":"https:\/\/www.clubempleos.com\/colombia\/wp-content\/uploads\/sites\/9\/2024\/08\/logo-de-la-organizacion.jpg","width":696,"height":696,"caption":"ClubEmpleos"},"image":{"@id":"https:\/\/www.clubempleos.com\/colombia\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/clubempleos.colombia\/","https:\/\/x.com\/clubempleos"]}]}},"_links":{"self":[{"href":"https:\/\/www.clubempleos.com\/colombia\/wp-json\/wp\/v2\/job-categories\/626","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.clubempleos.com\/colombia\/wp-json\/wp\/v2\/job-categories"}],"about":[{"href":"https:\/\/www.clubempleos.com\/colombia\/wp-json\/wp\/v2\/taxonomies\/job_listing_category"}],"up":[{"embeddable":true,"href":"https:\/\/www.clubempleos.com\/colombia\/wp-json\/wp\/v2\/job-categories\/613"}],"wp:post_type":[{"href":"https:\/\/www.clubempleos.com\/colombia\/wp-json\/wp\/v2\/job-listings?job-categories=626"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}